{"id":7832,"date":"2026-05-11T21:48:12","date_gmt":"2026-05-12T00:48:12","guid":{"rendered":"https:\/\/nabocadopovorn.com.br\/?p=7832"},"modified":"2026-05-11T21:48:15","modified_gmt":"2026-05-12T00:48:15","slug":"licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba","status":"publish","type":"post","link":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/","title":{"rendered":"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba"},"content":{"rendered":"\n<p>O licenciamento ambiental municipal de Maca\u00edba j\u00e1 come\u00e7a a se traduzir em desenvolvimento para a cidade, aliando desenvolvimento econ\u00f4mico, sustentabilidade e seguran\u00e7a jur\u00eddica. Lan\u00e7ado em agosto de 2025 pela Prefeitura, atrav\u00e9s da Secretaria Municipal de Meio Ambiente e Urbanismo (Semurb), o sistema pr\u00f3prio tem representado um novo horizonte de oportunidades para a atra\u00e7\u00e3o de investimentos e a consequente gera\u00e7\u00e3o de emprego e renda.<\/p>\n\n\n\n<p>Para se ter uma ideia, o \u00faltimo loteamento implantado em Maca\u00edba data de 2014. Em nove meses, a Semurb licenciou dois novos empreendimentos e possui outros seis em processamento. \u201cMaca\u00edba era a \u00fanica cidade da Regi\u00e3o Metropolitana que n\u00e3o tinha um sistema municipal de licenciamento. Por isso, muitos investidores preferiam as cidades vizinhas, por ser r\u00e1pido. Ent\u00e3o, a gest\u00e3o Em\u00eddio, com muita intelig\u00eancia e coragem, iniciou o processo para Maca\u00edba fazer seu pr\u00f3prio licenciamento ambiental, e isso j\u00e1 vem trazendo resultados vis\u00edveis. J\u00e1 temos dois novos loteamentos em execu\u00e7\u00e3o e mais seis em fase de an\u00e1lise para libera\u00e7\u00e3o e legaliza\u00e7\u00e3o\u201d, afirmou o titular da Semurb, Billy Jean.<\/p>\n\n\n\n<p>At\u00e9 o ano passado, as licen\u00e7as para novos empreendimentos no munic\u00edpio eram emitidas exclusivamente pelo Idema\/RN, o que demandava tempo consider\u00e1vel para a an\u00e1lise das solicita\u00e7\u00f5es em raz\u00e3o da alta demanda de todo o Estado. Desde a ado\u00e7\u00e3o do sistema municipal de licenciamentos, a Semurb tem recebido uma s\u00e9rie de pedidos de licenciamento para novos empreendimentos imobili\u00e1rios.<br>\u201cAprovamos a primeira legisla\u00e7\u00e3o ambiental e atualizamos as leis existentes, que trouxeram seguran\u00e7a jur\u00eddica \u00e0queles que desejam investir na nossa cidade. Vis\u00e3o estrat\u00e9gica e de futuro da nossa gest\u00e3o que colocaram Maca\u00edba num patamar de destaque no Rio Grande do Norte\u201d, afirmou o prefeito Em\u00eddio J\u00fanior.<\/p>\n\n\n\n<p>Imagem: Geraldo Neto<\/p>\n\n\n\n<p><strong>Fonte: Secom-PMM<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O licenciamento ambiental municipal de Maca\u00edba j\u00e1 come\u00e7a a se traduzir em desenvolvimento para a cidade, aliando desenvolvimento<\/p>\n","protected":false},"author":1,"featured_media":7833,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-7832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-macaiba"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba - Na Boca do Povo RN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba - Na Boca do Povo RN\" \/>\n<meta property=\"og:description\" content=\"O licenciamento ambiental municipal de Maca\u00edba j\u00e1 come\u00e7a a se traduzir em desenvolvimento para a cidade, aliando desenvolvimento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/\" \/>\n<meta property=\"og:site_name\" content=\"Na Boca do Povo RN\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T00:48:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T00:48:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nabocadopovorn.com.br\/wp-content\/uploads\/2026\/05\/campo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na Boca do Povo RN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na Boca do Povo RN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/\"},\"author\":{\"name\":\"Na Boca do Povo RN\",\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/#\\\/schema\\\/person\\\/4784d91e6eb0ee789392e2506451ee44\"},\"headline\":\"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba\",\"datePublished\":\"2026-05-12T00:48:12+00:00\",\"dateModified\":\"2026-05-12T00:48:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/campo.jpg\",\"articleSection\":[\"Maca\u00edba\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/\",\"url\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/\",\"name\":\"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba - Na Boca do Povo RN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/campo.jpg\",\"datePublished\":\"2026-05-12T00:48:12+00:00\",\"dateModified\":\"2026-05-12T00:48:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/campo.jpg\",\"contentUrl\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/campo.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/2026\\\/05\\\/11\\\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/#website\",\"url\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/\",\"name\":\"Na Boca do Povo RN\",\"description\":\"Informa\u00e7\u00e3o Total\",\"publisher\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/#organization\",\"name\":\"Na Boca do Povo RN\",\"url\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-LOGO-NOVA.png\",\"contentUrl\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-LOGO-NOVA.png\",\"width\":1024,\"height\":174,\"caption\":\"Na Boca do Povo RN\"},\"image\":{\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/#\\\/schema\\\/person\\\/4784d91e6eb0ee789392e2506451ee44\",\"name\":\"Na Boca do Povo RN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/568abe1cbc790e8c79eadb7595ddaf9dccc533c248b489d4b018b6c00965b6ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/568abe1cbc790e8c79eadb7595ddaf9dccc533c248b489d4b018b6c00965b6ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/568abe1cbc790e8c79eadb7595ddaf9dccc533c248b489d4b018b6c00965b6ea?s=96&d=mm&r=g\",\"caption\":\"Na Boca do Povo RN\"},\"sameAs\":[\"http:\\\/\\\/nabocadopovorn.com.br\"],\"url\":\"https:\\\/\\\/nabocadopovorn.com.br\\\/index.php\\\/author\\\/nabocadopovorn23gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba - Na Boca do Povo RN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/","og_locale":"pt_BR","og_type":"article","og_title":"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba - Na Boca do Povo RN","og_description":"O licenciamento ambiental municipal de Maca\u00edba j\u00e1 come\u00e7a a se traduzir em desenvolvimento para a cidade, aliando desenvolvimento","og_url":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/","og_site_name":"Na Boca do Povo RN","article_published_time":"2026-05-12T00:48:12+00:00","article_modified_time":"2026-05-12T00:48:15+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/nabocadopovorn.com.br\/wp-content\/uploads\/2026\/05\/campo.jpg","type":"image\/jpeg"}],"author":"Na Boca do Povo RN","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Na Boca do Povo RN","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/#article","isPartOf":{"@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/"},"author":{"name":"Na Boca do Povo RN","@id":"https:\/\/nabocadopovorn.com.br\/#\/schema\/person\/4784d91e6eb0ee789392e2506451ee44"},"headline":"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba","datePublished":"2026-05-12T00:48:12+00:00","dateModified":"2026-05-12T00:48:15+00:00","mainEntityOfPage":{"@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/"},"wordCount":329,"publisher":{"@id":"https:\/\/nabocadopovorn.com.br\/#organization"},"image":{"@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/#primaryimage"},"thumbnailUrl":"https:\/\/nabocadopovorn.com.br\/wp-content\/uploads\/2026\/05\/campo.jpg","articleSection":["Maca\u00edba"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/","url":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/","name":"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba - Na Boca do Povo RN","isPartOf":{"@id":"https:\/\/nabocadopovorn.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/#primaryimage"},"image":{"@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/#primaryimage"},"thumbnailUrl":"https:\/\/nabocadopovorn.com.br\/wp-content\/uploads\/2026\/05\/campo.jpg","datePublished":"2026-05-12T00:48:12+00:00","dateModified":"2026-05-12T00:48:15+00:00","breadcrumb":{"@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/#primaryimage","url":"https:\/\/nabocadopovorn.com.br\/wp-content\/uploads\/2026\/05\/campo.jpg","contentUrl":"https:\/\/nabocadopovorn.com.br\/wp-content\/uploads\/2026\/05\/campo.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/nabocadopovorn.com.br\/index.php\/2026\/05\/11\/licenciamento-ambiental-municipal-impulsiona-desenvolvimento-de-macaiba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nabocadopovorn.com.br\/"},{"@type":"ListItem","position":2,"name":"Licenciamento ambiental municipal impulsiona desenvolvimento de Maca\u00edba"}]},{"@type":"WebSite","@id":"https:\/\/nabocadopovorn.com.br\/#website","url":"https:\/\/nabocadopovorn.com.br\/","name":"Na Boca do Povo RN","description":"Informa\u00e7\u00e3o Total","publisher":{"@id":"https:\/\/nabocadopovorn.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nabocadopovorn.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nabocadopovorn.com.br\/#organization","name":"Na Boca do Povo RN","url":"https:\/\/nabocadopovorn.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nabocadopovorn.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/nabocadopovorn.com.br\/wp-content\/uploads\/2026\/05\/cropped-LOGO-NOVA.png","contentUrl":"https:\/\/nabocadopovorn.com.br\/wp-content\/uploads\/2026\/05\/cropped-LOGO-NOVA.png","width":1024,"height":174,"caption":"Na Boca do Povo RN"},"image":{"@id":"https:\/\/nabocadopovorn.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nabocadopovorn.com.br\/#\/schema\/person\/4784d91e6eb0ee789392e2506451ee44","name":"Na Boca do Povo RN","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/568abe1cbc790e8c79eadb7595ddaf9dccc533c248b489d4b018b6c00965b6ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/568abe1cbc790e8c79eadb7595ddaf9dccc533c248b489d4b018b6c00965b6ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/568abe1cbc790e8c79eadb7595ddaf9dccc533c248b489d4b018b6c00965b6ea?s=96&d=mm&r=g","caption":"Na Boca do Povo RN"},"sameAs":["http:\/\/nabocadopovorn.com.br"],"url":"https:\/\/nabocadopovorn.com.br\/index.php\/author\/nabocadopovorn23gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7832"}],"version-history":[{"count":1,"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7832\/revisions"}],"predecessor-version":[{"id":7834,"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7832\/revisions\/7834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/media\/7833"}],"wp:attachment":[{"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nabocadopovorn.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}